{"id":4852,"date":"2026-05-27T09:07:27","date_gmt":"2026-05-27T07:07:27","guid":{"rendered":"https:\/\/goldenesrosenkreuz.ch\/?post_type=tribe_events&#038;p=4852"},"modified":"2026-08-10T17:01:56","modified_gmt":"2026-08-10T15:01:56","slug":"rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde","status":"publish","type":"tribe_events","link":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/","title":{"rendered":"Portes ouvertes"},"content":{"rendered":"<p>Depuis des mill\u00e9naires, l\u2019humanit\u00e9 est en marche.<br \/>\nDes inscriptions dans la pierre, des papyrus, des livres, des vies de pri\u00e8re, de d\u00e9vouement ou d\u2019actes h\u00e9ro\u00efques n\u2019ont cess\u00e9 de t\u00e9moigner de la tentative d\u2019\u00e9l\u00e9vation de l\u2019\u00eatre humain. Mais si cette tentative s\u2019est r\u00e9v\u00e9l\u00e9e tr\u00e8s enrichissante dans bien des cas, n\u2019a-t-elle pas trop souvent abouti \u00e0 l\u2019intol\u00e9rance et \u00e0 la violence ? Qu\u2019en est-il aujourd\u2019hui ?<\/p>\n<p>Le c\u0153ur de l\u2019\u00eatre humain est-il encore anim\u00e9 par ce m\u00eame d\u00e9sir, cette m\u00eame aspiration \u00e0 l\u2019\u00e9l\u00e9vation ? Il y a actuellement un foisonnement de courants spirituels, des plus ouverts aux plus intol\u00e9rants, des plus pacifiques aux plus violents, des plus profonds aux plus superficiels.<\/p>\n<p>Il y a de vrais ma\u00eetres spirituels et de parfaits imposteurs. Comment s\u2019y retrouver ? Et qu\u2019est-ce que je recherche r\u00e9ellement ? Le mieux-\u00eatre, la paix, l\u2019harmonie, l\u2019\u00e9l\u00e9vation ?<\/p>\n<p>Suis-je sensible \u00e0 la d\u00e9tresse qui touche tant d\u2019\u00eatres ? Suis-je troubl\u00e9 par les \u00e9v\u00e9nements qui secouent le monde ?<\/p>\n<p>Comment est-ce que je r\u00e9agis face au d\u00e9ferlement d\u2019informations \u00e0 la t\u00e9l\u00e9vision et sur les r\u00e9seaux sociaux ? Comment puis-je discerner le vrai du faux, trouver la perle dans la fange ? O\u00f9 puiser la confiance en moi, la foi in\u00e9branlable dans la vie ? Autant de questions que nous tenterons d\u2019approfondir et auxquelles nous essayerons de r\u00e9pondre au cours de la soir\u00e9e \u00ab Portes ouvertes \u00bb, le lundi 14 d\u00e9cembre (18h-20h). Entr\u00e9e libre, sans inscription.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis des mill\u00e9naires, l\u2019humanit\u00e9 est en marche. Des inscriptions dans la pierre, des papyrus, des livres, des vies de pri\u00e8re, de d\u00e9vouement ou d\u2019actes h\u00e9ro\u00efques n\u2019ont cess\u00e9 de t\u00e9moigner de la tentative d\u2019\u00e9l\u00e9vation de l\u2019\u00eatre humain. Mais si cette tentative s\u2019est r\u00e9v\u00e9l\u00e9e tr\u00e8s enrichissante dans bien des cas, n\u2019a-t-elle pas trop souvent abouti \u00e0 l\u2019intol\u00e9rance et \u00e0 la violence ? Qu\u2019en est-il aujourd\u2019hui ? Le c\u0153ur de l\u2019\u00eatre humain est-il encore anim\u00e9 par ce m\u00eame d\u00e9sir, cette m\u00eame aspiration \u00e0 l\u2019\u00e9l\u00e9vation ? Il y a actuellement un foisonnement de courants spirituels, des plus ouverts aux plus intol\u00e9rants, des plus pacifiques<\/p>\n","protected":false},"author":5,"featured_media":4933,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[104,122],"class_list":["post-4852","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-centre-de-sion","tribe_events_cat-portes-ouvertes","cat_centre-de-sion","cat_portes-ouvertes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portes ouvertes - Rose Croix d&#039;Or<\/title>\n<meta name=\"description\" content=\"-641\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portes ouvertes - Rose Croix d&#039;Or\" \/>\n<meta property=\"og:description\" content=\"-641\" \/>\n<meta property=\"og:url\" content=\"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/\" \/>\n<meta property=\"og:site_name\" content=\"Goldenes Rosenkreuz\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-10T15:01:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/\",\"url\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/\",\"name\":\"Portes ouvertes - Rose Croix d'Or\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Portes-ouvertes-centre-de-Sion-2026.avif\",\"datePublished\":\"2026-05-27T07:07:27+00:00\",\"dateModified\":\"2026-08-10T15:01:56+00:00\",\"description\":\"-641\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Portes-ouvertes-centre-de-Sion-2026.avif\",\"contentUrl\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Portes-ouvertes-centre-de-Sion-2026.avif\",\"width\":\"1672\",\"height\":\"941\",\"caption\":\"Portes ouvertes centre de Sion 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/event\\\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Portes ouvertes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/\",\"name\":\"Goldenes Rosenkreuz\",\"description\":\"Gnosis heute\",\"publisher\":{\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/#organization\",\"name\":\"Goldenes Rosenkreuz Schweiz\",\"url\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/favicon-196x196-3.png\",\"contentUrl\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/favicon-196x196-3.png\",\"width\":196,\"height\":196,\"caption\":\"Goldenes Rosenkreuz Schweiz\"},\"image\":{\"@id\":\"https:\\\/\\\/goldenesrosenkreuz.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portes ouvertes - Rose Croix d'Or","description":"-641","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/","og_locale":"fr_FR","og_type":"article","og_title":"Portes ouvertes - Rose Croix d'Or","og_description":"-641","og_url":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/","og_site_name":"Goldenes Rosenkreuz","article_modified_time":"2026-08-10T15:01:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/","url":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/","name":"Portes ouvertes - Rose Croix d'Or","isPartOf":{"@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/#primaryimage"},"image":{"@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/#primaryimage"},"thumbnailUrl":"https:\/\/goldenesrosenkreuz.ch\/wp-content\/uploads\/2026\/05\/Portes-ouvertes-centre-de-Sion-2026.avif","datePublished":"2026-05-27T07:07:27+00:00","dateModified":"2026-08-10T15:01:56+00:00","description":"-641","breadcrumb":{"@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/#primaryimage","url":"https:\/\/goldenesrosenkreuz.ch\/wp-content\/uploads\/2026\/05\/Portes-ouvertes-centre-de-Sion-2026.avif","contentUrl":"https:\/\/goldenesrosenkreuz.ch\/wp-content\/uploads\/2026\/05\/Portes-ouvertes-centre-de-Sion-2026.avif","width":"1672","height":"941","caption":"Portes ouvertes centre de Sion 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/event\/rencontre-au-centre-de-sion-a-la-decouverte-de-notre-source-profonde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/goldenesrosenkreuz.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/goldenesrosenkreuz.ch\/fr\/events\/"},{"@type":"ListItem","position":3,"name":"Portes ouvertes"}]},{"@type":"WebSite","@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/#website","url":"https:\/\/goldenesrosenkreuz.ch\/fr\/","name":"Goldenes Rosenkreuz","description":"Gnosis heute","publisher":{"@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/goldenesrosenkreuz.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/#organization","name":"Goldenes Rosenkreuz Schweiz","url":"https:\/\/goldenesrosenkreuz.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/goldenesrosenkreuz.ch\/wp-content\/uploads\/2022\/12\/favicon-196x196-3.png","contentUrl":"https:\/\/goldenesrosenkreuz.ch\/wp-content\/uploads\/2022\/12\/favicon-196x196-3.png","width":196,"height":196,"caption":"Goldenes Rosenkreuz Schweiz"},"image":{"@id":"https:\/\/goldenesrosenkreuz.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/4852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":5,"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/4852\/revisions"}],"predecessor-version":[{"id":4941,"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/4852\/revisions\/4941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/media\/4933"}],"wp:attachment":[{"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/media?parent=4852"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/tags?post=4852"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/goldenesrosenkreuz.ch\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=4852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}